{"id":1583,"date":"2020-12-03T13:18:53","date_gmt":"2020-12-03T16:18:53","guid":{"rendered":"http:\/\/eduvir.com.br\/hmlg\/?post_type=cases&#038;p=1583"},"modified":"2022-01-13T16:41:59","modified_gmt":"2022-01-13T19:41:59","slug":"normas-regulamentadoras","status":"publish","type":"cases","link":"http:\/\/eduvir.com.br\/novo\/cases\/normas-regulamentadoras\/","title":{"rendered":"NR\u00b4s &#8211; Normas Regulamentadoras"},"content":{"rendered":"<p>NR 4 \u2013 Equipamentos de Prote\u00e7\u00e3o Coletiva (EPC\u2019s)<br \/>\nNR 5 \u2013 Comiss\u00e3o Interna de Preven\u00e7\u00e3o de Acidentes (CIPA)<br \/>\nNR 6 \u2013 Equipamentos de Prote\u00e7\u00e3o Individual (EPI)<br \/>\nNR 9 \u2013 Programa de Preven\u00e7\u00e3o de Riscos Ambientais (PPRA)<br \/>\nNR 10 \u2013 Seguran\u00e7a em Instala\u00e7\u00f5es e Servi\u00e7os em Eletricidade<br \/>\nNR 17 \u2013 Ergonomia<br \/>\nNR 33 \u2013 Seguran\u00e7a e Sa\u00fade nos Trabalhos em Espa\u00e7os Confinados<br \/>\nNR 35 \u2013 Trabalho em Altura<\/p>\n<p><b>P\u00fablico-Alvo:<br \/>\n<\/b>Trabalhadores envolvidos em atividades com riscos espec\u00edficos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1588 size-medium\" src=\"http:\/\/eduvir.com.br\/novo\/wp-content\/uploads\/2020\/12\/NR-300x163.png\" alt=\"\" width=\"300\" height=\"163\" srcset=\"http:\/\/eduvir.com.br\/novo\/wp-content\/uploads\/2020\/12\/NR-300x163.png 300w, http:\/\/eduvir.com.br\/novo\/wp-content\/uploads\/2020\/12\/NR.png 496w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"featured_media":0,"template":"","_links":{"self":[{"href":"http:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/cases\/1583"}],"collection":[{"href":"http:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/cases"}],"about":[{"href":"http:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/types\/cases"}],"wp:attachment":[{"href":"http:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/media?parent=1583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}