{"id":1237,"date":"2020-12-21T12:30:16","date_gmt":"2020-12-21T15:30:16","guid":{"rendered":"http:\/\/eduvir.com.br\/hmlg\/?post_type=clippings&#038;p=1237"},"modified":"2020-12-21T12:30:16","modified_gmt":"2020-12-21T15:30:16","slug":"exposicao-rio-mais-design-no-pallazzo-affari-ai-giureconsulti-da-camara-de-comercio-industria-a-piazza-mercanti-2-milao-04-2009","status":"publish","type":"clippings","link":"https:\/\/eduvir.com.br\/novo\/clippings\/exposicao-rio-mais-design-no-pallazzo-affari-ai-giureconsulti-da-camara-de-comercio-industria-a-piazza-mercanti-2-milao-04-2009\/","title":{"rendered":"Exposi\u00e7\u00e3o Rio Mais Design, no Pallazzo Affari ai Giureconsulti da C\u00e2mara de Com\u00e9rcio, Ind\u00fastria, \u00e0 Piazza Mercanti, 2. Mil\u00e3o \u2013 04\/2009"},"content":{"rendered":"<p>Participa\u00e7\u00e3o de designers cariocas renomados e premiados internacionalmente.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":0,"template":"","_links":{"self":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/clippings\/1237"}],"collection":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/clippings"}],"about":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/types\/clippings"}],"wp:attachment":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/media?parent=1237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}