{"id":1241,"date":"2020-12-21T12:42:13","date_gmt":"2020-12-21T15:42:13","guid":{"rendered":"http:\/\/eduvir.com.br\/hmlg\/?post_type=clippings&#038;p=1241"},"modified":"2020-12-21T12:42:13","modified_gmt":"2020-12-21T15:42:13","slug":"casa-com-br-10-2010","status":"publish","type":"clippings","link":"https:\/\/eduvir.com.br\/novo\/clippings\/casa-com-br-10-2010\/","title":{"rendered":"Casa.com.br \u2013 10\/2010"},"content":{"rendered":"<p>Casa Cor Rio de Janeiro abre suas portas em noite de coquetel.<\/p>\n<p>Para marcar o come\u00e7o da Casa Cor Rio de Janeiro, no \u00faltimo dia 30 de agosto, convidados especiais foram recebidos na pr\u00f3pria loca\u00e7\u00e3o em um coquetel animado.<\/p>\n","protected":false},"featured_media":0,"template":"","_links":{"self":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/clippings\/1241"}],"collection":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/clippings"}],"about":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/types\/clippings"}],"wp:attachment":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/media?parent=1241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}