{"id":3953,"date":"2024-10-18T11:42:33","date_gmt":"2024-10-18T14:42:33","guid":{"rendered":"https:\/\/eduvir.com.br\/novo\/?p=3953"},"modified":"2024-10-18T11:42:33","modified_gmt":"2024-10-18T14:42:33","slug":"carreira-e-pessoal-e-intransferivel","status":"publish","type":"post","link":"https:\/\/eduvir.com.br\/novo\/2024\/10\/18\/carreira-e-pessoal-e-intransferivel\/","title":{"rendered":"Carreira \u00e9 Pessoal e Intransfer\u00edvel"},"content":{"rendered":"<h3 id=\"ember1387\" class=\"ember-view reader-text-block__heading-3\">Voc\u00ea pensa nos pr\u00f3ximos passos da carreira de forma antecipada?<\/h3>\n<p id=\"ember1388\" class=\"ember-view reader-text-block__paragraph\">Eu me formei em engenharia qu\u00edmica e como fui sempre muito planejada (ou preocupada, pois precisa trabalhar), um semestre antes de me formar j\u00e1 tinha feito provas para dois mestrados e estava participando de in\u00fameros processos seletivos. O plano A era trabalhar e o plano B seria fazer mestrado caso n\u00e3o conseguisse emprego. A \u00e9poca era horr\u00edvel. O pa\u00eds estava em crise com quase nenhuma oportunidade para minha \u00e1rea.<\/p>\n<p id=\"ember1389\" class=\"ember-view reader-text-block__paragraph\">Ainda assim, consegui entrar em uma empresa de consultoria e, no primeiro dia, j\u00e1 estava em campo, realizando auditoria de seguran\u00e7a, sa\u00fade e meio ambiente numa grande multinacional. Eu n\u00e3o tive nenhum treinamento formal, mas acompanhava um auditor muito experiente, que me ensinou valiosas li\u00e7\u00f5es \u2013 mesmo sem eu saber, ele foi meu primeiro mentor.<\/p>\n<h3 id=\"ember1390\" class=\"ember-view reader-text-block__heading-3\">A observa\u00e7\u00e3o \u00e9 uma ferramenta poderosa para sua carreira<\/h3>\n<p id=\"ember1391\" class=\"ember-view reader-text-block__paragraph\">Durante esse per\u00edodo, aprendi algo fundamental: a import\u00e2ncia de observar e absorver conhecimento. Eu anotava tudo em meu caderno. Sempre adorei cadernos e canetas. Escrever era a forma que tinha de sedimentar o aprendizado. Eu sempre o encontrava na sa\u00edda do metr\u00f4 e \u00edamos de carro at\u00e9 a empresa. Eu aproveitava cada segundo do tempo de transporte para fazer perguntas e entender o m\u00e1ximo poss\u00edvel.<\/p>\n<p id=\"ember1392\" class=\"ember-view reader-text-block__paragraph\">Ele tinha um jeito s\u00e9rio, formal, fechado, mas como viu que eu estava muito interessada, come\u00e7ou a me ensinar muito. Ficamos pr\u00f3ximos e eu sentia que ele tinha prazer em responder minhas in\u00fameras perguntas.<\/p>\n<p id=\"ember1393\" class=\"ember-view reader-text-block__paragraph\">Eu nem sabia o que era mentoria nessa \u00e9poca, mas esse profissional foi meu primeiro mentor informal, que me deu uma base s\u00f3lida para avan\u00e7ar, e, apesar de n\u00e3o chamar isso de &#8220;mentoria&#8221; na \u00e9poca, ele representou exatamente isso: orienta\u00e7\u00e3o e direcionamento.<\/p>\n<p id=\"ember1394\" class=\"ember-view reader-text-block__paragraph\">A mentoria \u00e9 um\u00a0programa de orienta\u00e7\u00e3o\u00a0que visa ajudar o indiv\u00edduo a realizar mudan\u00e7as na carreira, explorar novas oportunidades profissionais e alcan\u00e7ar novos marcos em sua trajet\u00f3ria profissional.<\/p>\n<h3 id=\"ember1395\" class=\"ember-view reader-text-block__heading-3\">Voc\u00ea tem sede de conhecimento e busca oportunidades de aprendizado?<\/h3>\n<p id=\"ember1396\" class=\"ember-view reader-text-block__paragraph\">O conhecimento daquele auditor me inspirou a investir ainda mais na minha carreira. No meu primeiro ano de formada, j\u00e1 iniciei uma p\u00f3s-gradua\u00e7\u00e3o em Seguran\u00e7a do Trabalho. Sabia que precisava aprender muito para ser uma profissional de destaque, mas tamb\u00e9m percebi o valor de ter uma orienta\u00e7\u00e3o profissional ao meu lado.<\/p>\n<p id=\"ember1397\" class=\"ember-view reader-text-block__paragraph\">Em um determinado momento da carreira, eu tinha inquietudes com as mudan\u00e7as que estava fazendo na carreira, se eu estava na empresa certa e se no futuro o mercado me absorveria bem.\u00a0Foi quando procurei ajuda externa e contratei uma psic\u00f3loga que, sem saber, estava me oferecendo mentoria de carreira. N\u00e3o se usava essa palavra. Ela era de uma grande empresa de Outplacement e atuava como consultora. Fiz v\u00e1rios testes psicol\u00f3gicos, tivemos v\u00e1rias sess\u00f5es de exerc\u00edcios, alinhamento e aconselhamento.\u00a0Ela me ajudou a entender meus pontos fortes, minhas ambi\u00e7\u00f5es e como poderia me posicionar melhor. Com esse apoio, meus avan\u00e7os foram muito mais estrat\u00e9gicos e r\u00e1pidos.<\/p>\n<p id=\"ember1398\" class=\"ember-view reader-text-block__paragraph\">Eu sempre tive p\u00e2nico de ficar sem emprego. Vim de uma fam\u00edlia muito simples e desde 11 anos de idade, a \u00fanica coisa que eu pensava era em me formar para dar uma vida melhor para meus pais.<\/p>\n<p id=\"ember1399\" class=\"ember-view reader-text-block__paragraph\">O resultado foi inusitado. Consegui entender as pol\u00edticas e as din\u00e2micas internas das organiza\u00e7\u00f5es. Percebi que tinha fit psicol\u00f3gico com a empresa que estava e que era um celeiro f\u00e9rtil para minha carreira.<\/p>\n<p id=\"ember1400\" class=\"ember-view reader-text-block__paragraph\">Hoje as empresas j\u00e1 t\u00eam mecanismos de checagem de fit cultural e muitas j\u00e1 possuem mentores internos e contratar um mentor de carreira externo \u00e9 muito f\u00e1cil.<\/p>\n<h3 id=\"ember1401\" class=\"ember-view reader-text-block__heading-3\">As dores de quem est\u00e1 insatisfeito com a carreira<\/h3>\n<p id=\"ember1402\" class=\"ember-view reader-text-block__paragraph\">Cheguei a um ponto em que n\u00e3o me sentia reconhecida e valorizada. Eu j\u00e1 geria equipes, tinha responsabilidades de gerente, mas n\u00e3o tinha o cargo ou o sal\u00e1rio correspondente. Estava em um ciclo de frustra\u00e7\u00e3o. Outros profissionais avan\u00e7avam, mas eu me perguntava o que faltava para mim. Talvez, se eu tivesse um mentor nesse momento, os resultados teriam vindo mais r\u00e1pido.<\/p>\n<p id=\"ember1403\" class=\"ember-view reader-text-block__paragraph\"><strong>Voc\u00ea \u00e9 protagonista da sua carreira?<\/strong><\/p>\n<p id=\"ember1404\" class=\"ember-view reader-text-block__paragraph\">Eu j\u00e1 sabia que n\u00e3o devemos esperar que as coisas simplesmente aconte\u00e7am, mas \u00e0s vezes a vida n\u00e3o permite que voc\u00ea d\u00ea conta da carreira, pois outras prioridades surgem.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3955\" src=\"http:\/\/eduvir.com.br\/novo\/wp-content\/uploads\/2024\/10\/Texto-MH-18.10-II-300x168.png\" alt=\"\" width=\"567\" height=\"318\" srcset=\"https:\/\/eduvir.com.br\/novo\/wp-content\/uploads\/2024\/10\/Texto-MH-18.10-II-300x168.png 300w, https:\/\/eduvir.com.br\/novo\/wp-content\/uploads\/2024\/10\/Texto-MH-18.10-II.png 634w\" sizes=\"(max-width: 567px) 100vw, 567px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p id=\"ember1407\" class=\"ember-view reader-text-block__paragraph\">Precisamos ser protagonistas. Eu me coloquei em movimento, tanto dentro da empresa quanto no mercado de trabalho, e fui em busca de novos caminhos. Quando comecei a agir intencionalmente, tudo come\u00e7ou a fluir. Entrei em uma espiral positiva e, aos poucos, as oportunidades come\u00e7aram a surgir.<\/p>\n<p id=\"ember1408\" class=\"ember-view reader-text-block__paragraph\">Primeiro fiz movimentos na pr\u00f3pria empresa. Multipliquei interfaces e fazia quest\u00e3o de que outras pessoas e gestores me conhecessem para que considerassem meu trabalho e indiretamente fizessem elogios ou recomenda\u00e7\u00f5es positivas de mim.\u00a0Fui muito cuidadosa e dedicada ao meu trabalho. Mais do que nunca, queria resultados extraordin\u00e1rios. Conversava com muitos gestores, colegas e equipes para ouvir a opini\u00e3o sobre minhas fraquezas e pontos fortes. Estava empenhad\u00edssima em melhorar e fazer uma virada.<\/p>\n<p id=\"ember1409\" class=\"ember-view reader-text-block__paragraph\">Fiz movimentos tamb\u00e9m fora da empresa. Tudo que voc\u00ea \u00e9 no mercado pode reverberar dentro da empresa. Ent\u00e3o, tratei de movimentar o mundo ao meu redor.<\/p>\n<p>. Fiz um MBA;<br \/>\n. Fui selecionada para uma oportunidade em outra empresa;<br \/>\n. Passei em um concurso p\u00fablico importante para minha \u00e1rea;<br \/>\n. Fui premiada com uma viagem para fora do Brasil por desempenho;<br \/>\n. Mudei para o apartamento dos sonhos;<br \/>\n. Fui promovida a gerente.<\/p>\n<p id=\"ember1416\" class=\"ember-view reader-text-block__paragraph\">Quando voc\u00ea entra em movimento parece que o universo conspira a seu favor. O fato \u00e9 que fiz uma enxurrada de movimentos. \u00a0Trabalhei e estudei muito nesse per\u00edodo, tracei estrat\u00e9gias e executei meus planos.<\/p>\n<p id=\"ember1417\" class=\"ember-view reader-text-block__paragraph\">Deu certo. Mas&#8230;<\/p>\n<p id=\"ember1418\" class=\"ember-view reader-text-block__paragraph\">Se eu tivesse uma mentora, talvez o esfor\u00e7o n\u00e3o fosse t\u00e3o grande e o resultado poderia ser mais r\u00e1pido.<\/p>\n<p id=\"ember1419\" class=\"ember-view reader-text-block__paragraph\"><strong>O que a mentoria pode fazer por voc\u00ea?<\/strong><\/p>\n<p id=\"ember1420\" class=\"ember-view reader-text-block__paragraph\">A mentoria de carreira \u00e9 um presente. Ela amplia seu olhar sobre voc\u00ea mesmo, ajuda a planejar seus passos com precis\u00e3o e evita o desperd\u00edcio de tempo em caminhos incertos. Um mentor \u00e9 quem te desafia, te apoia e te impulsiona a ser a melhor vers\u00e3o de voc\u00ea na sua jornada profissional.<\/p>\n<p id=\"ember1421\" class=\"ember-view reader-text-block__paragraph\">O mentor \u00e9 algu\u00e9m que te ajuda a atravessar a ponte. Algu\u00e9m que viveu essas experi\u00eancias, oferece aconselhamento e <em>insights<\/em> valiosos, compartilha viv\u00eancias profissionais e prop\u00f5e exerc\u00edcios atrav\u00e9s de ferramentas que auxiliem no autoconhecimento e a tra\u00e7ar uma estrat\u00e9gia para alcan\u00e7ar seu objetivo.<\/p>\n<p id=\"ember1422\" class=\"ember-view reader-text-block__paragraph\">Hoje, sempre digo para minhas filhas: somos m\u00faltiplos. Podemos ter v\u00e1rias carreiras, pertencer a diversas tribos, e o mundo est\u00e1 repleto de possibilidades. N\u00e3o precisamos nos limitar a um \u00fanico caminho.<\/p>\n<p id=\"ember1423\" class=\"ember-view reader-text-block__paragraph\">Se temos tantas aptid\u00f5es, podemos ser v\u00e1rias coisas. Por que queremos nos limitar sempre a uma \u00fanica coisa ou um \u00fanico caminho?<\/p>\n<p id=\"ember1424\" class=\"ember-view reader-text-block__paragraph\">Eu mesma sou uma mentora de carreira bem engenheira, aquela que adora m\u00e9tricas. Sei que, como engenheira qu\u00edmica, sou uma sens\u00edvel psic\u00f3loga organizacional. Sou a professora mais crian\u00e7a que existe, pois botava as bonecas para dar aula. Ainda bem que redescobri isso a tempo de voltar a esse lugar. Sou a escritora adolescente que escondia os escritos da m\u00e3e e que hoje se sente realizada por estar escrevendo um livro. Sou a m\u00e3e da gera\u00e7\u00e3o X aprendiz de tecnologia com as filhas mentora nativas digitais da gera\u00e7\u00e3o Z. Sou a 50+ \u201cadolescente na maturidade\u201d que est\u00e1 fazendo mais uma transi\u00e7\u00e3o de carreira e a estudante 50+ empolgada como se fosse uma jovem universit\u00e1ria.<\/p>\n<p id=\"ember1425\" class=\"ember-view reader-text-block__paragraph\"><strong>Assuma o Protagonismo da Sua Carreira<\/strong><\/p>\n<p>1. A carreira n\u00e3o pode ser deixada ao acaso; cada passo deve ser intencional.<br \/>\n2. A observa\u00e7\u00e3o \u00e9 uma ferramenta poderosa para aprender com quem tem mais experi\u00eancia.<br \/>\n3. Investir em conhecimento cont\u00ednuo \u00e9 essencial para se destacar no mercado competitivo.<br \/>\n4. A mentoria acelera resultados e oferece estrat\u00e9gia personalizada para se desenvolver.<br \/>\n5. A estagna\u00e7\u00e3o sem orienta\u00e7\u00e3o pode atrasar seu progresso; um mentor encurta caminhos.<br \/>\n6. Seja o protagonista da sua carreira; esteja em movimento e agindo de forma proativa.<br \/>\n7. Networking e visibilidade dentro e fora da empresa s\u00e3o importantes para seu avan\u00e7o.<br \/>\n8. Quando voc\u00ea toma atitudes consistentes, o universo parece conspirar a seu favor.<br \/>\n9. Ter v\u00e1rias habilidades e interesses te permite explorar m\u00faltiplos caminhos e n\u00e3o se limitar.<br \/>\n10. O sucesso na carreira \u00e9 resultado de decis\u00f5es conscientes e do aprendizado cont\u00ednuo, n\u00e3o de sorte ou circunst\u00e2ncia.<\/p>\n<h3 id=\"ember1437\" class=\"ember-view reader-text-block__heading-3\">Voc\u00ea est\u00e1 pronto(a) para assumir os passos do seu futuro?<\/h3>\n<p id=\"ember1438\" class=\"ember-view reader-text-block__paragraph\">N\u00e3o perca mais tempo. Cada passo pode ser um avan\u00e7o significativo para a carreira que voc\u00ea deseja.<\/p>\n<p id=\"ember1439\" class=\"ember-view reader-text-block__paragraph\">Agende agora sua sess\u00e3o de #mentoria e descubra o que est\u00e1 ao seu alcance!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea pensa nos pr\u00f3ximos passos da carreira de forma antecipada? Eu me formei em engenharia qu\u00edmica e como fui sempre muito planejada (ou preocupada, pois precisa trabalhar), um semestre antes de me formar j\u00e1 tinha feito provas para dois mestrados e estava participando de in\u00fameros processos seletivos. O plano A era trabalhar e o plano [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":3954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[159,457,458],"_links":{"self":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/posts\/3953"}],"collection":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/comments?post=3953"}],"version-history":[{"count":3,"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/posts\/3953\/revisions"}],"predecessor-version":[{"id":3958,"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/posts\/3953\/revisions\/3958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/media\/3954"}],"wp:attachment":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/media?parent=3953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/categories?post=3953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/tags?post=3953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}