{"id":458,"date":"2020-12-16T23:18:28","date_gmt":"2020-12-17T02:18:28","guid":{"rendered":"http:\/\/eduvir.com.br\/hmlg\/?p=458"},"modified":"2020-12-16T23:18:28","modified_gmt":"2020-12-17T02:18:28","slug":"e-se-no-final-tudo-der-certo-por-cris-chiavenato","status":"publish","type":"post","link":"https:\/\/eduvir.com.br\/novo\/2020\/12\/16\/e-se-no-final-tudo-der-certo-por-cris-chiavenato\/","title":{"rendered":"E SE, NO FINAL, TUDO DER CERTO? por Cris Chiavenato"},"content":{"rendered":"<p>Sempre que estamos preocupados com algo, seja com nossa sa\u00fade f\u00edsica, com algum relacionamento, com nossa situa\u00e7\u00e3o financeira, com dilemas no trabalho, com nossos filhos, etc.,\u00a0<strong>\u00e9 comum focarmos no negativo, ou seja,\u00a0no que n\u00e3o queremos que aconte\u00e7a!<\/strong><\/p>\n<p>Isso ocorre porque nossa mente presta mais aten\u00e7\u00e3o no negativo do que no positivo. Se tivermos nove acontecimentos positivos no nosso dia e somente um acontecimento negativo, de qual voc\u00ea vai se lembrar mais?<\/p>\n<p>Pesquisadores acreditam que a\u00a0capacidade de enfatizar o negativo \u00e9 resultado de um fen\u00f4meno evolutivo. Desde nossos prim\u00f3rdios, estar consciente e evitar o perigo t\u00eam sido uma habilidade fundamental para a sobreviv\u00eancia do ser humano. O psic\u00f3logo e cientista Dr. Rick Hanson diz que nossos c\u00e9rebros s\u00e3o\u00a0<em>\u201cVelcro para a negatividade e Teflon para a positividade\u201d.\u00a0<\/em>O que ocorre \u00e9 que nossas preocupa\u00e7\u00f5es, infelizmente, aderem nas nossas mentes muito mais do que nossas experi\u00eancias positivas.<\/p>\n<p>Eu vejo esse fen\u00f4meno acontecendo diariamente com meus clientes de Coaching, com as pessoas ao meu redor, e \u00e0s vezes comigo mesma. O importante \u00e9 que, com uma pr\u00e1tica simples, podemos reverter essa negatividade.<\/p>\n<p>Um dos meus clientes (<em>coachee<\/em>) queria ser promovido no trabalho, mas n\u00e3o sabia se seria capaz de exercer bem as novas fun\u00e7\u00f5es. Ele j\u00e1 tinha pleiteado a promo\u00e7\u00e3o uma vez, sem \u00eaxito, ent\u00e3o, naturalmente, estava com receio de tentar novamente.<\/p>\n<p>Em uma das nossas sess\u00f5es, eu pedi para ele fazer o seguinte exerc\u00edcio: escrever todo e qualquer pensamento que o estava incomodando \u2013 pensamentos negativos \u2013 com rela\u00e7\u00e3o \u00e0 t\u00e3o desejada promo\u00e7\u00e3o, come\u00e7ando com: E se\u2026<\/p>\n<p>A lista dele ficou mais ou menos assim:<\/p>\n<ul>\n<li>E se eu aplicar para a promo\u00e7\u00e3o novamente, mas n\u00e3o for aceito?<\/li>\n<li>E se eu for aceito, mas n\u00e3o conseguir exercer bem as minhas fun\u00e7\u00f5es?<\/li>\n<li>E se eu n\u00e3o \u201cder conta\u201d do trabalho?<\/li>\n<li>E se as pessoas me julgarem por isso?<\/li>\n<li>E se eu ficar estressado com o novo cargo?<\/li>\n<li>E se eu acabar saindo do meu equil\u00edbrio?<\/li>\n<li>E se eu perder o emprego por estar fazendo algo al\u00e9m das minhas habilidades?<\/li>\n<\/ul>\n<p>Depois que ele tomou consci\u00eancia de todos os pensamentos negativos que estava tendo, eu pedi para ele fazer outra lista supondo que tudo daria certo.<\/p>\n<p>A nova lista ficou assim:<\/p>\n<ul>\n<li>E se eu aplicar para o novo cargo, e for aceito?<\/li>\n<li>E se eu me der super bem no novo cargo?<\/li>\n<li>E se eu conseguir me organizar para fazer tudo o que preciso?<\/li>\n<li>E se eu tiver ajudantes eficientes, que facilitem o meu trabalho?<\/li>\n<li>E se eu me surpreender comigo mesmo?<\/li>\n<li>E se a minha capacidade for muito al\u00e9m do que eu imagino?<\/li>\n<li>E se eu conseguir me manter equilibrado emocionalmente?<\/li>\n<li>E se essa promo\u00e7\u00e3o me trouxer muitas surpresas agrad\u00e1veis?<\/li>\n<li>E se o Universo estiver conspirando ao meu favor?<\/li>\n<li>E se, no final, tudo der certo?<\/li>\n<\/ul>\n<p>Que mudan\u00e7a! Esse exerc\u00edcio \u00e9 muito simples, mas muito poderoso! Ele transforma nossa energia rapidamente. Com uma energia mais positiva, ficamos mais leves de corpo e alma e abrimos espa\u00e7o para a criatividade fluir e para encontrarmos solu\u00e7\u00f5es para nossos problemas. \u00c9 poss\u00edvel sentirmos a tens\u00e3o amenizando no nosso corpo no momento em que mudamos nosso foco.<\/p>\n<p>A verdade \u00e9 que temos a tend\u00eancia de fazer suposi\u00e7\u00f5es negativas \u2013 como no \u201c<em>Velcro para a negatividade\u201d<\/em>\u00a0\u2013 sem nem sabermos qual vai ser o resultado final da quest\u00e3o.<\/p>\n<p>Se n\u00e3o sabemos com certeza se vamos \u201cfalhar\u201d ou se vai dar \u201ctudo errado\u201d \u2013 e \u00e9 imposs\u00edvel sabermos com seguran\u00e7a \u2013 qual \u00e9 a vantagem de antecipar ou sofrer por algo negativo que pode nem mesmo vir a acontecer? Voc\u00ea j\u00e1 percebeu que a maioria das nossas expectativas e previs\u00f5es negativas nunca acontece?<\/p>\n<p>Da pr\u00f3xima vez que voc\u00ea estiver preocupado com algo, identifique os seus pensamentos negativos, como foi feito no caso acima,\u00a0e transforme-os para possibilidades positivas \u2013\u00a0<em>E se, no final, tudo der certo?!\u00a0\u00a0\u00a0<\/em><\/p>\n<p>Assim voc\u00ea vai agir em dire\u00e7\u00e3o aos seus objetivos com mais confian\u00e7a e otimismo, e ter\u00e1 mais chances de alcan\u00e7ar o que deseja.<\/p>\n<p>Aguardo seus coment\u00e1rios!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sempre que estamos preocupados com algo, seja com nossa sa\u00fade f\u00edsica, com algum relacionamento, com nossa situa\u00e7\u00e3o financeira, com dilemas no trabalho, com nossos filhos, etc.,\u00a0\u00e9 comum focarmos no negativo, ou seja,\u00a0no que n\u00e3o queremos que aconte\u00e7a! Isso ocorre porque nossa mente presta mais aten\u00e7\u00e3o no negativo do que no positivo. Se tivermos nove acontecimentos [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":459,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/posts\/458"}],"collection":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/comments?post=458"}],"version-history":[{"count":1,"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/posts\/458\/revisions"}],"predecessor-version":[{"id":460,"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/posts\/458\/revisions\/460"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/media\/459"}],"wp:attachment":[{"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/media?parent=458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/categories?post=458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eduvir.com.br\/novo\/wp-json\/wp\/v2\/tags?post=458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}